{"id":244,"date":"2020-08-19T14:49:25","date_gmt":"2020-08-19T12:49:25","guid":{"rendered":"https:\/\/persist.erasmus.site\/?page_id=244"},"modified":"2020-08-19T15:12:34","modified_gmt":"2020-08-19T13:12:34","slug":"download","status":"publish","type":"page","link":"https:\/\/persist.erasmus.site\/es\/download\/","title":{"rendered":"Download"},"content":{"rendered":"<p><\/p>\n<h2 style=\"text-align: center;\">Newsletters<\/h2>\n<div class=\"row\">\n<div class=\"col-sm-3\" style=\"text-align: center;\"><a href=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1_ESP.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117 aligncenter\" style=\"box-shadow: 5px 5px 10px; color: green;\" src=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg\" alt=\"\" width=\"212\" height=\"300\" \/><br \/>\nNewsletter 1<\/a><\/div>\n<div class=\"col-sm-3\" style=\"text-align: center;\"><a href=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW2_SP.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117 aligncenter\" style=\"box-shadow: 5px 5px 10px; color: green;\" src=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW2-page-001-scaled-e1597824749839.jpg\" alt=\"\" width=\"212\" height=\"300\" \/><br \/>\nNewsletter 2<\/a><\/div>\n<div class=\"col-sm-3\" style=\"text-align: center;\"><a href=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW3_ES.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117 aligncenter\" style=\"box-shadow: 5px 5px 10px; color: green;\" src=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW3_FINAL-page-001-scaled-e1597825059113.jpg\" alt=\"\" width=\"212\" height=\"300\" \/><br \/>\nNewsletter 3<\/a><\/div>\n<h2 style=\"text-align: center;\">Poster<\/h2>\n<div class=\"row\">\n<div class=\"col-sm-3\" style=\"text-align: center;\"><a href=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_POSTER-60x80_SPANISH.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117 aligncenter\" style=\"box-shadow: 5px 5px 10px; color: green;\" src=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_POSTER-60x80_English-page-001-scaled-e1597829261119.jpg\" alt=\"\" width=\"212\" height=\"283\" \/><br \/>\nProject Poster<\/a><\/div>\n<div class=\"col-sm-3\" style=\"text-align: center;\"><a href=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_POSTER-60x80_ENGLISH_CONFERENCE-.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117 aligncenter\" style=\"box-shadow: 5px 5px 10px; color: green;\" src=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_POSTER-60x80_ENGLISH_CONFERENCE-page-001-scaled-e1597829573359.jpg\" alt=\"\" width=\"212\" height=\"283\" \/><br \/>\nProject Poster &#8211; Conference<\/a><\/div>\n<\/div>\n<h2 style=\"text-align: center;\">Leaflet<\/h2>\n<div class=\"row\">\n<div class=\"col-sm-12\" style=\"text-align: center;\"><a href=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/LEAFLET_trifold_A4_Persist_spanish.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117 aligncenter\" style=\"box-shadow: 5px 5px 10px; color: green;\" src=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/LEAFLET_trifold_A4_Persist-page-001-e1597827841652.jpg\" alt=\"\" width=\"300\" height=\"212\" \/><br \/>\nProject Leaflet<\/a><\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<div class=\"slide-text-bg2\"><span>Newsletters Newsletter 1 Newsletter 2 Newsletter 3 Poster Project Poster Project Poster &#8211; Conference Leaflet Project Leaflet<\/span><\/div>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"fullwidth.php","meta":{"footnotes":""},"class_list":["post-244","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Download - PERSIST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/persist.erasmus.site\/es\/download\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Download - PERSIST\" \/>\n<meta property=\"og:description\" content=\"Newsletters Newsletter 1 Newsletter 2 Newsletter 3 Poster Project Poster Project Poster &#8211; Conference Leaflet Project Leaflet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/persist.erasmus.site\/es\/download\/\" \/>\n<meta property=\"og:site_name\" content=\"PERSIST\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PersistEU\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-19T13:12:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Persist_EU\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/\",\"url\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/\",\"name\":\"Download - PERSIST\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/download\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/persist.erasmus.site\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg\",\"datePublished\":\"2020-08-19T12:49:25+00:00\",\"dateModified\":\"2020-08-19T13:12:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/#primaryimage\",\"url\":\"https:\\\/\\\/persist.erasmus.site\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg\",\"contentUrl\":\"https:\\\/\\\/persist.erasmus.site\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/download\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Download\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/\",\"name\":\"PERSIST\",\"description\":\"Knowledge, beliefs, Perceptions about Science of European Students\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/persist.erasmus.site\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Download - PERSIST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/persist.erasmus.site\/es\/download\/","og_locale":"es_ES","og_type":"article","og_title":"Download - PERSIST","og_description":"Newsletters Newsletter 1 Newsletter 2 Newsletter 3 Poster Project Poster Project Poster &#8211; Conference Leaflet Project Leaflet","og_url":"https:\/\/persist.erasmus.site\/es\/download\/","og_site_name":"PERSIST","article_publisher":"https:\/\/www.facebook.com\/PersistEU","article_modified_time":"2020-08-19T13:12:34+00:00","og_image":[{"url":"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Persist_EU","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/persist.erasmus.site\/es\/download\/","url":"https:\/\/persist.erasmus.site\/es\/download\/","name":"Download - PERSIST","isPartOf":{"@id":"https:\/\/persist.erasmus.site\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/persist.erasmus.site\/es\/download\/#primaryimage"},"image":{"@id":"https:\/\/persist.erasmus.site\/download\/#primaryimage"},"thumbnailUrl":"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg","datePublished":"2020-08-19T12:49:25+00:00","dateModified":"2020-08-19T13:12:34+00:00","breadcrumb":{"@id":"https:\/\/persist.erasmus.site\/es\/download\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/persist.erasmus.site\/es\/download\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/persist.erasmus.site\/es\/download\/#primaryimage","url":"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg","contentUrl":"https:\/\/persist.erasmus.site\/wp-content\/uploads\/2020\/08\/PERSIST_NW1-page-001-scaled-e1597824501324.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/persist.erasmus.site\/es\/download\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/persist.erasmus.site\/es\/"},{"@type":"ListItem","position":2,"name":"Download"}]},{"@type":"WebSite","@id":"https:\/\/persist.erasmus.site\/es\/#website","url":"https:\/\/persist.erasmus.site\/es\/","name":"PERSIST","description":"Knowledge, beliefs, Perceptions about Science of European Students","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/persist.erasmus.site\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/pages\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/comments?post=244"}],"version-history":[{"count":0,"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/pages\/244\/revisions"}],"wp:attachment":[{"href":"https:\/\/persist.erasmus.site\/es\/wp-json\/wp\/v2\/media?parent=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}