{"id":126,"date":"2019-11-10T12:03:10","date_gmt":"2019-11-10T11:03:10","guid":{"rendered":"https:\/\/persist.erasmus.site\/?page_id=126"},"modified":"2020-03-04T14:36:03","modified_gmt":"2020-03-04T13:36:03","slug":"platform","status":"publish","type":"page","link":"https:\/\/persist.erasmus.site\/sk\/platform\/","title":{"rendered":"Online platforma"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"slide-text-bg2\"><span><\/span><\/div>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-126","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online platforma  - PERSIST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/persist.erasmus.site\/sk\/platform\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online platforma  - PERSIST\" \/>\n<meta property=\"og:url\" content=\"https:\/\/persist.erasmus.site\/sk\/platform\/\" \/>\n<meta property=\"og:site_name\" content=\"PERSIST\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PersistEU\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-04T13:36:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Persist_EU\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/platform\\\/\",\"url\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/platform\\\/\",\"name\":\"Online platforma  - PERSIST\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/#website\"},\"datePublished\":\"2019-11-10T11:03:10+00:00\",\"dateModified\":\"2020-03-04T13:36:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/platform\\\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/platform\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/platform\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online platform\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/#website\",\"url\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/\",\"name\":\"PERSIST\",\"description\":\"Knowledge, beliefs, Perceptions about Science of European Students\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/persist.erasmus.site\\\/sk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online platforma  - PERSIST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/persist.erasmus.site\/sk\/platform\/","og_locale":"sk_SK","og_type":"article","og_title":"Online platforma  - PERSIST","og_url":"https:\/\/persist.erasmus.site\/sk\/platform\/","og_site_name":"PERSIST","article_publisher":"https:\/\/www.facebook.com\/PersistEU","article_modified_time":"2020-03-04T13:36:03+00:00","twitter_card":"summary_large_image","twitter_site":"@Persist_EU","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/persist.erasmus.site\/sk\/platform\/","url":"https:\/\/persist.erasmus.site\/sk\/platform\/","name":"Online platforma  - PERSIST","isPartOf":{"@id":"https:\/\/persist.erasmus.site\/sk\/#website"},"datePublished":"2019-11-10T11:03:10+00:00","dateModified":"2020-03-04T13:36:03+00:00","breadcrumb":{"@id":"https:\/\/persist.erasmus.site\/sk\/platform\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/persist.erasmus.site\/sk\/platform\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/persist.erasmus.site\/sk\/platform\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/persist.erasmus.site\/sk\/"},{"@type":"ListItem","position":2,"name":"Online platform"}]},{"@type":"WebSite","@id":"https:\/\/persist.erasmus.site\/sk\/#website","url":"https:\/\/persist.erasmus.site\/sk\/","name":"PERSIST","description":"Knowledge, beliefs, Perceptions about Science of European Students","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/persist.erasmus.site\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"}]}},"_links":{"self":[{"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/pages\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":0,"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/pages\/126\/revisions"}],"wp:attachment":[{"href":"https:\/\/persist.erasmus.site\/sk\/wp-json\/wp\/v2\/media?parent=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}